{"id":575,"date":"2009-02-25T17:35:37","date_gmt":"2009-02-25T17:35:37","guid":{"rendered":"https:\/\/giannaguide.com\/?p=575"},"modified":"2022-07-29T12:48:37","modified_gmt":"2022-07-29T12:48:37","slug":"i-della-robbia-21-febbraio-7-giugno-2009-museo-statale-darte-medievale-e-moderna","status":"publish","type":"post","link":"https:\/\/giannaguide.com\/fr\/2009\/02\/25\/i-della-robbia-21-febbraio-7-giugno-2009-museo-statale-darte-medievale-e-moderna\/","title":{"rendered":"I DELLA ROBBIA &#8211; 21 febbraio > 7 giugno 2009 Museo Statale d&#8217;Arte Medievale e Moderna"},"content":{"rendered":"<p>\u00c8 finalmente aperta la mostra sui Della Robbia: le sale sono affollate di opere splendenti, colorate e luminescenti; si passa fra ali di personaggi espressivi e quasi a grandezza naturale, sotto gli occhi di Madonne colte in un momento di tenerezza e appagamento &#8211; Madonna di Palaia, con le mani che tengono stretto il Figlio, premendo le dita sulla tenera carne \u2013 Madonna della mela del Bargello, Madonne piangenti al centro di un dolore corale \u2013 Piet\u00e0 fra S. Giovanni Evangelista e la Maddalena del Bargello. Vi si vedono anche lesene, canestri di fiori e frutta, piccoli animali, mattonelle, pale d\u2019altare, quadretti, vasi, stemmi\u2026 tutto realizzato in terracotta invetriata, \u201cun\u2019arte nuova, utile e bellissima\u201d secondo il Vasari, che ci informa che Luca \u201cfaceva l\u2019opere di terra quasi eterne\u201d. Il successo fu grande: le opere erano innovative, economiche, durevoli, incredibilmente belle e adatte a decorare gli ambienti rinascimentali; nell\u2019arco di un secolo esse invasero Firenze, la Toscana, l\u2019Italia e anche molti paesi dell\u2019 Europa occidentale. Con Luca lavor\u00f2 molto il nipote Andrea e dopo continuarono tutti i suoi cinque figli maschi: Giovanni, Marco, Francesco, Luca il Giovane e Girolamo Della Robbia. Solo in provincia di Arezzo sono presenti pi\u00f9 di 160 opere robbiane: un vero museo diffuso in Casentino (Bibbiena, Castel Focognano, Santuario della Verna, Montemignaio, Poppi, Pratovecchio, Stia), Valdarno (Bucine, Cavriglia, Montevarchi, San Giovanni Valdarno, Terranuova Bracciolini), Valdichiana (Castiglion Fiorentino, Civitella in Valdichiana, Cortona, Foiano della Chiana, Lucignano, Monte S. Savino) e Valtiberina (Anghiari, Badia Tedalda, Monterchi, Pieve S. Stefano, Sansepolcro, Sestino).<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c8 finalmente aperta la mostra sui Della Robbia: le sale sono affollate di opere splendenti, colorate e luminescenti; si passa fra ali di personaggi espressivi e quasi a grandezza naturale, sotto gli occhi di Madonne colte in un momento di tenerezza e appagamento &#8211; Madonna di Palaia, con le mani che tengono stretto il Figlio, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[8],"tags":[],"class_list":["post-575","post","type-post","status-publish","format-standard","hentry","category-eventi"],"_links":{"self":[{"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":2,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"predecessor-version":[{"id":577,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/posts\/575\/revisions\/577"}],"wp:attachment":[{"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giannaguide.com\/fr\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}